{"id":27,"count":8,"description":"","link":"https:\/\/behnsbestper.com\/Availability\/product-category\/ferns\/","name":"Ferns","slug":"ferns","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/behnsbestper.com\/Availability\/wp-json\/wp\/v2\/product_cat\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/behnsbestper.com\/Availability\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/behnsbestper.com\/Availability\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/behnsbestper.com\/Availability\/wp-json\/wp\/v2\/product?product_cat=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}